{"id":3999,"count":1,"description":"","link":"https:\/\/konek.com.pl\/de\/tag\/mercedes-benz-code-b8-0111131008812\/","name":"mercedes-benz code B8 0111131008812","slug":"mercedes-benz-code-b8-0111131008812","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/tags\/3999"}],"collection":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/posts?tags=3999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}