{"id":4351,"count":1,"description":"","link":"https:\/\/konek.com.pl\/de\/tag\/psa-code-e24-53-920-g\/","name":"psa code E24.53.920.G","slug":"psa-code-e24-53-920-g","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/tags\/4351"}],"collection":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/konek.com.pl\/de\/wp-json\/wp\/v2\/posts?tags=4351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}