{"id":2665,"count":1,"description":"","link":"https:\/\/konek.com.pl\/w\/tag\/locating-pins-m303-02\/","name":"locating pins M303-02","slug":"locating-pins-m303-02","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/konek.com.pl\/w\/wp-json\/wp\/v2\/tags\/2665"}],"collection":[{"href":"https:\/\/konek.com.pl\/w\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/konek.com.pl\/w\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/konek.com.pl\/w\/wp-json\/wp\/v2\/posts?tags=2665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}